{
    "id": 7598,
    "date": "2022-02-06T22:23:46",
    "date_gmt": "2022-02-06T18:53:46",
    "guid": {
        "rendered": "http:\/\/pncertificate.com\/en\/?p=7598"
    },
    "modified": "2022-02-06T22:41:54",
    "modified_gmt": "2022-02-06T19:11:54",
    "slug": "el-reputacion-que-saco-maria-del-carmen-para",
    "status": "publish",
    "type": "post",
    "link": "https:\/\/pncertificate.com\/fa_ir\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/",
    "title": {
        "rendered": "El reputacion que saco Maria del Carmen para pagarle al estafador"
    },
    "content": {
        "rendered": "<p><title>El reputacion que saco Maria del Carmen para pagarle al estafador<\/title><\/p>\n<p>Aunque el paquete seguia en Malasia.<\/p>\n<p>A Estela le llego otro mensaje de el courier, Airo Speed: debia abonar otros 2 mil dolares en pensamiento sobre con total seguridad de obtener descargar definitivamente el paquete con el iPhone 7 Plus, el iPad Air, los juegos de joyas, el auricular con traduccion simultanea, la computadora Apple, el argolla de diamantes asi\u00ad como, especialmente, la rosado de plastico con el dinero.<!--more--><\/p>\n<p>Estela ya estaba agotada y nunca entendia. No queria las regalos. Ni pagar mas. &#8220;Hola, es urgente, en la actualidad estan pidiendo un pago sobre fiable que no fue lo que dijeron ayer, yo creo que deberi\u00adan soltar la mercaderia porque la multa Ahora fue abonada -le escribio a James, desesperada-. Nunca podria realizar ese pago porque ninguna cosa garantiza que despues pongan mas trabas, creo que la entidad de mensajeria tiene que replicar juridicamente por todos las danos ocasiones. Estoy bastante tragico asi\u00ad como no tengo garantias de que abonando parecido suma de dinero eso llegue a destino (. ) La realidad estas complicaciones me aportan mal. Lo que tu digas yo hare&#8221;.<\/p>\n<h2>El fin sobre la empeno<\/h2>\n<p>Estuvo a momento de realizar el otro viraje. Incluso que el parecer de una sobre sus mas intimas amigas le hizo darse cuenta de que era la estafa. &#8220;inclusive aca llegue. La empresa que te perjudico pagara por los danos y En Caso De Que tu eres un alma noble entenderas desplazandolo hacia el pelo sino la vida se encargara sobre que muchas indisposicion terminal asi\u00ad como bastante dolorosa pagues por los danos ocasionados. No me importa: el dinero va y viene, desplazandolo hacia el pelo nunca lo necesito -le escribio a James, con rabia-. Lo lamentable de este universo podri\u00ada ser huviese clases como vos. Robaste la identidad sobre un pobre arquetipo, jugaste con vaya a saber cuantas chicas, por suerte Con El Fin De mi Tinder es un esparcimiento. Es Durante la reciente ocasion que me ocurre esto, fuiste un muy lindo formacion, debido, aprendi que Existen mentes muy enfermas asi\u00ad como sos la sobre esas. Hasta la proxima vida. Mamarracho&#8221;.<\/p>\n<p>James respondio que ese mail era lo infimo que le habia pasado &#8220;despues de el fallecimiento de su esposa&#8221;. &#8220;Estoy excesivamente herido. Pense que lo que compartimos era apego verdadero, ciertamente me rompe el corazon que esto ya suceda en el primer inconveniente que encontramos igual que marido asi\u00ad como femina&#8221;.<\/p>\n<h2>Maria del Carmen si pago<\/h2>\n<p>Ese igual mes, otras victimas argentinas Ahora habian caido en sus manos: una contadora mendocina que llego a frenar el pago de la &#8220;encomienda&#8221;, igual que publico Los Andes. No obstante por lo menos siete hembras hacen pagos por medio de Western Union a Malasia, an apelativo de una mujer conocida por Estela: Hariati Binti Aning. En todos los casos con la misma modalidad: un match en Tinder, trueque dilatado de <a href=\"https:\/\/besthookupwebsites.org\/es\/usasexguide-review\/\">usasexguide para pc<\/a> mensajes amorosos, un supuesto emision sobre regalos, desplazandolo hacia el pelo todo mientras el protagonista, ingeniero nuclear, se encontraba sobre viaje en lugares remotos, inaccesibles y aislados. James Ferguson fue muchas ocasii?n Martin Adams, Harry Trump y Robert Jude.<\/p>\n<p>Estela evito caer en la segunda traspaso. No obstante Maria del Carmen (no es su sustantivo real), otra chica sobre cincuenta anos de vida que buscaba reconocer gente por medio de Tinder, no corrio con la misma &#8220;suerte&#8221;: abono la sancion y despues el fiable de el envio. Despues de hacerlo, los pedidos de dinero siguieron; igual que el monto que le enviaba la persona que se hacia llamar James Ferguson ascendia a mas de 80 mil dolares, debia crearse un perfil del banco con el fin de  que se lo pudieran traspasar, ya que era ella la beneficiaria del remision. La novia accedio con la exigencia de seguidamente pudiera devolverle el dinero a Ferguson.<\/p>",
        "protected": false
    },
    "excerpt": {
        "rendered": "<p>El reputacion que saco Maria del Carmen para pagarle al estafador Aunque el paquete seguia en Malasia. A Estela le llego otro mensaje de el courier, Airo Speed: debia abonar otros 2 mil dolares en pensamiento sobre con total seguridad de obtener descargar definitivamente el paquete con el iPhone 7 Plus, el iPad Air, los [&hellip;]<\/p>",
        "protected": false
    },
    "author": 2,
    "featured_media": 0,
    "comment_status": "open",
    "ping_status": "open",
    "sticky": false,
    "template": "",
    "format": "standard",
    "meta": {
        "footnotes": ""
    },
    "categories": [
        1964
    ],
    "tags": [],
    "class_list": [
        "post-7598",
        "post",
        "type-post",
        "status-publish",
        "format-standard",
        "hentry",
        "category-usasexguies-es-review-2"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El reputacion que saco Maria del Carmen para pagarle al estafador - \u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pncertificate.com\/fa_ir\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El reputacion que saco Maria del Carmen para pagarle al estafador - \u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646\" \/>\n<meta property=\"og:description\" content=\"El reputacion que saco Maria del Carmen para pagarle al estafador Aunque el paquete seguia en Malasia. A Estela le llego otro mensaje de el courier, Airo Speed: debia abonar otros 2 mil dolares en pensamiento sobre con total seguridad de obtener descargar definitivamente el paquete con el iPhone 7 Plus, el iPad Air, los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pncertificate.com\/fa_ir\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-06T18:53:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-06T19:11:54+00:00\" \/>\n<meta name=\"author\" content=\"Parvaneh behrouzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\" \/>\n\t<meta name=\"twitter:data1\" content=\"Parvaneh behrouzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/\"},\"author\":{\"name\":\"Parvaneh behrouzi\",\"@id\":\"https:\/\/pncertificate.com\/#\/schema\/person\/f3ccec08f07a9cbc9b64099da14eb366\"},\"headline\":\"El reputacion que saco Maria del Carmen para pagarle al estafador\",\"datePublished\":\"2022-02-06T18:53:46+00:00\",\"dateModified\":\"2022-02-06T19:11:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/\"},\"wordCount\":655,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/pncertificate.com\/#organization\"},\"articleSection\":[\"usasexguies es review\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/\",\"url\":\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/\",\"name\":\"El reputacion que saco Maria del Carmen para pagarle al estafador - \u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646\",\"isPartOf\":{\"@id\":\"https:\/\/pncertificate.com\/#website\"},\"datePublished\":\"2022-02-06T18:53:46+00:00\",\"dateModified\":\"2022-02-06T19:11:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#breadcrumb\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u062e\u0627\u0646\u0647\",\"item\":\"https:\/\/pncertificate.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El reputacion que saco Maria del Carmen para pagarle al estafador\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pncertificate.com\/#website\",\"url\":\"https:\/\/pncertificate.com\/\",\"name\":\"\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646\",\"description\":\"\u0635\u062f\u0648\u0631 \u0627\u0646\u0648\u0627\u0639 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 \u0648 \u0645\u062f\u0627\u0631\u06a9 \u0645\u0639\u062a\u0628\u0631\",\"publisher\":{\"@id\":\"https:\/\/pncertificate.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pncertificate.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pncertificate.com\/#organization\",\"name\":\"\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646\",\"url\":\"https:\/\/pncertificate.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/pncertificate.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pncertificate.com\/wp-content\/uploads\/2021\/11\/cropped-logo25-26.png\",\"contentUrl\":\"https:\/\/pncertificate.com\/wp-content\/uploads\/2021\/11\/cropped-logo25-26.png\",\"width\":533,\"height\":115,\"caption\":\"\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646\"},\"image\":{\"@id\":\"https:\/\/pncertificate.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/pncertificate.com\/#\/schema\/person\/f3ccec08f07a9cbc9b64099da14eb366\",\"name\":\"Parvaneh behrouzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/pncertificate.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5f298942e1cec98f016b6645d3cc6a3387340211f414c99212a2cb69da4bf1a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5f298942e1cec98f016b6645d3cc6a3387340211f414c99212a2cb69da4bf1a7?s=96&d=mm&r=g\",\"caption\":\"Parvaneh behrouzi\"},\"url\":\"https:\/\/pncertificate.com\/fa_ir\/author\/parvaneh-behrouzi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "El reputacion que saco Maria del Carmen para pagarle al estafador - \u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/pncertificate.com\/fa_ir\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/",
        "og_locale": "fa_IR",
        "og_type": "article",
        "og_title": "El reputacion que saco Maria del Carmen para pagarle al estafador - \u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646",
        "og_description": "El reputacion que saco Maria del Carmen para pagarle al estafador Aunque el paquete seguia en Malasia. A Estela le llego otro mensaje de el courier, Airo Speed: debia abonar otros 2 mil dolares en pensamiento sobre con total seguridad de obtener descargar definitivamente el paquete con el iPhone 7 Plus, el iPad Air, los [&hellip;]",
        "og_url": "https:\/\/pncertificate.com\/fa_ir\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/",
        "og_site_name": "\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646",
        "article_published_time": "2022-02-06T18:53:46+00:00",
        "article_modified_time": "2022-02-06T19:11:54+00:00",
        "author": "Parvaneh behrouzi",
        "twitter_card": "summary_large_image",
        "twitter_misc": {
            "\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a": "Parvaneh behrouzi",
            "\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646": "3 \u062f\u0642\u06cc\u0642\u0647"
        },
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "Article",
                    "@id": "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#article",
                    "isPartOf": {
                        "@id": "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/"
                    },
                    "author": {
                        "name": "Parvaneh behrouzi",
                        "@id": "https:\/\/pncertificate.com\/#\/schema\/person\/f3ccec08f07a9cbc9b64099da14eb366"
                    },
                    "headline": "El reputacion que saco Maria del Carmen para pagarle al estafador",
                    "datePublished": "2022-02-06T18:53:46+00:00",
                    "dateModified": "2022-02-06T19:11:54+00:00",
                    "mainEntityOfPage": {
                        "@id": "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/"
                    },
                    "wordCount": 655,
                    "commentCount": 0,
                    "publisher": {
                        "@id": "https:\/\/pncertificate.com\/#organization"
                    },
                    "articleSection": [
                        "usasexguies es review"
                    ],
                    "inLanguage": "fa-IR",
                    "potentialAction": [
                        {
                            "@type": "CommentAction",
                            "name": "Comment",
                            "target": [
                                "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#respond"
                            ]
                        }
                    ]
                },
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/",
                    "url": "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/",
                    "name": "El reputacion que saco Maria del Carmen para pagarle al estafador - \u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646",
                    "isPartOf": {
                        "@id": "https:\/\/pncertificate.com\/#website"
                    },
                    "datePublished": "2022-02-06T18:53:46+00:00",
                    "dateModified": "2022-02-06T19:11:54+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#breadcrumb"
                    },
                    "inLanguage": "fa-IR",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/pncertificate.com\/en\/2022\/02\/06\/el-reputacion-que-saco-maria-del-carmen-para\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "\u062e\u0627\u0646\u0647",
                            "item": "https:\/\/pncertificate.com\/en\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "El reputacion que saco Maria del Carmen para pagarle al estafador"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/pncertificate.com\/#website",
                    "url": "https:\/\/pncertificate.com\/",
                    "name": "\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646",
                    "description": "\u0635\u062f\u0648\u0631 \u0627\u0646\u0648\u0627\u0639 \u06af\u0648\u0627\u0647\u06cc\u0646\u0627\u0645\u0647 \u0648 \u0645\u062f\u0627\u0631\u06a9 \u0645\u0639\u062a\u0628\u0631",
                    "publisher": {
                        "@id": "https:\/\/pncertificate.com\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/pncertificate.com\/?s={search_term_string}"
                            },
                            "query-input": "required name=search_term_string"
                        }
                    ],
                    "inLanguage": "fa-IR"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/pncertificate.com\/#organization",
                    "name": "\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646",
                    "url": "https:\/\/pncertificate.com\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "fa-IR",
                        "@id": "https:\/\/pncertificate.com\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/pncertificate.com\/wp-content\/uploads\/2021\/11\/cropped-logo25-26.png",
                        "contentUrl": "https:\/\/pncertificate.com\/wp-content\/uploads\/2021\/11\/cropped-logo25-26.png",
                        "width": 533,
                        "height": 115,
                        "caption": "\u0635\u062f\u0648\u0631 \u06af\u0648\u0627\u0647\u06cc \u0648 \u0645\u062f\u0631\u06a9 \u067e\u06cc \u0627\u0646"
                    },
                    "image": {
                        "@id": "https:\/\/pncertificate.com\/#\/schema\/logo\/image\/"
                    }
                },
                {
                    "@type": "Person",
                    "@id": "https:\/\/pncertificate.com\/#\/schema\/person\/f3ccec08f07a9cbc9b64099da14eb366",
                    "name": "Parvaneh behrouzi",
                    "image": {
                        "@type": "ImageObject",
                        "inLanguage": "fa-IR",
                        "@id": "https:\/\/pncertificate.com\/#\/schema\/person\/image\/",
                        "url": "https:\/\/secure.gravatar.com\/avatar\/5f298942e1cec98f016b6645d3cc6a3387340211f414c99212a2cb69da4bf1a7?s=96&d=mm&r=g",
                        "contentUrl": "https:\/\/secure.gravatar.com\/avatar\/5f298942e1cec98f016b6645d3cc6a3387340211f414c99212a2cb69da4bf1a7?s=96&d=mm&r=g",
                        "caption": "Parvaneh behrouzi"
                    },
                    "url": "https:\/\/pncertificate.com\/fa_ir\/author\/parvaneh-behrouzi\/"
                }
            ]
        }
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/posts\/7598",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/posts"
            }
        ],
        "about": [
            {
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/types\/post"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/users\/2"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/comments?post=7598"
            }
        ],
        "version-history": [
            {
                "count": 0,
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/posts\/7598\/revisions"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/media?parent=7598"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "category",
                "embeddable": true,
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/categories?post=7598"
            },
            {
                "taxonomy": "post_tag",
                "embeddable": true,
                "href": "https:\/\/pncertificate.com\/fa_ir\/wp-json\/wp\/v2\/tags?post=7598"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}